{"id":1033,"date":"2017-09-26T22:17:05","date_gmt":"2017-09-26T20:17:05","guid":{"rendered":"http:\/\/www.ringen-traunstein.de\/wp\/?p=1033"},"modified":"2017-09-26T22:25:12","modified_gmt":"2017-09-26T20:25:12","slug":"jahreshauptversammlung-foerderverein","status":"publish","type":"post","link":"https:\/\/www.ringen-traunstein.de\/wp\/jahreshauptversammlung-foerderverein\/","title":{"rendered":"Jahreshauptversammlung F\u00f6rderverein"},"content":{"rendered":"<p><strong>Jahreshauptversammlung des F\u00f6rdervereins<\/strong><\/p>\n<p>Donnerstag, 28. September um 19:30 Uhr im Wochinger Brauhaus (Nebenzimmer) in Traunstein, Oswaldstra\u00dfe.<\/p>\n<p>Tagesordnung:<span class=\"text_exposed_show\"><br \/>\no Begr\u00fc\u00dfung und Bericht durch den 1. Vorsitzenden<br \/>\no Kassenbericht durch den Kassierer<br \/>\no Auskunft \u00fcber die Kassenpr\u00fcfung<br \/>\no Entlastung des Vorstands<br \/>\no Neuwahlen des Vorstands (1.und 2.Vorsitzender, Kassier)<br \/>\no Bericht des Abteilungsleiters der Ringerabteilung \u00fcber die Situation der Abteilung und den weiteren sportlichen Verlauf im Jahre 2017 (Liga, Sportler, usw.)<br \/>\no Vorschl\u00e4ge, W\u00fcnsche und Antr\u00e4ge<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>\u00dcber ein zahlreiches Erscheinen w\u00fcrden wir uns freuen.<\/p>\n<p>Mit sportlichen Gr\u00fc\u00dfen<\/p>\n<p>1. Vorsitzender<br \/>\nChristian Einsiedler<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jahreshauptversammlung des F\u00f6rdervereins Donnerstag, 28. September um 19:30 Uhr im Wochinger Brauhaus (Nebenzimmer) in Traunstein, Oswaldstra\u00dfe. Tagesordnung: o Begr\u00fc\u00dfung und Bericht durch den 1. Vorsitzenden o Kassenbericht durch den Kassierer&#8230; <a href=\"https:\/\/www.ringen-traunstein.de\/wp\/jahreshauptversammlung-foerderverein\/\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1033","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/posts\/1033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/comments?post=1033"}],"version-history":[{"count":1,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/posts\/1033\/revisions"}],"predecessor-version":[{"id":1034,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/posts\/1033\/revisions\/1034"}],"wp:attachment":[{"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/media?parent=1033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/categories?post=1033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ringen-traunstein.de\/wp\/wp-json\/wp\/v2\/tags?post=1033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}